{"id":949,"date":"2024-09-26T10:52:48","date_gmt":"2024-09-26T08:52:48","guid":{"rendered":"https:\/\/www.saintetheresechalons.com\/?page_id=949"},"modified":"2026-01-17T15:34:02","modified_gmt":"2026-01-17T14:34:02","slug":"jeunes-7-18-ans","status":"publish","type":"page","link":"https:\/\/www.saintetheresechalons.com\/index.php\/jeunes-7-18-ans\/","title":{"rendered":"Jeunes (7 &#8211; 18 ans)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il est possible de pr\u00e9parer le bapt\u00eame \u00e0 tout \u00e2ge<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trois groupes existent sur le doyenn\u00e9, un pour les primaires, un pour les coll\u00e9giens et un pour les lyc\u00e9ens.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pour les primaires :<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9unions le mercredi 10h \u00e0 11h30 au presbyt\u00e8re de la paroisse sainte Th\u00e9r\u00e8se,140 &nbsp;avenue du G\u00e9n\u00e9ral de Gaulle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pour les coll\u00e9giens :<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9unions le mercredi de 14h30 \u00e0 16h au 1 place Notre Dame et Dame et participation aux 24h pour Dieu le week-end du 1er et 2 f\u00e9vrier<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pour les lyc\u00e9ens<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">10 r\u00e9unions le dimanche de 15h30 \u00e0 17h au 1 Place Notre Dame <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est possible de pr\u00e9parer le bapt\u00eame \u00e0 tout \u00e2ge Trois groupes existent sur le doyenn\u00e9, un pour les primaires, un pour les coll\u00e9giens et un pour les lyc\u00e9ens. Pour &#8230; <span class=\"more\"><a class=\"more-link\" href=\"https:\/\/www.saintetheresechalons.com\/index.php\/jeunes-7-18-ans\/\">[Read more&#8230;]<\/a><\/span><\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["entry","page","publish","author-markholds","post-949"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jeunes (7 - 18 ans) - Paroisse Sainte-Th\u00e9r\u00e8se<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.saintetheresechalons.com\/index.php\/jeunes-7-18-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jeunes (7 - 18 ans) - Paroisse Sainte-Th\u00e9r\u00e8se\" \/>\n<meta property=\"og:description\" content=\"Il est possible de pr\u00e9parer le bapt\u00eame \u00e0 tout \u00e2ge Trois groupes existent sur le doyenn\u00e9, un pour les primaires, un pour les coll\u00e9giens et un pour les lyc\u00e9ens. Pour ... [Read more...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.saintetheresechalons.com\/index.php\/jeunes-7-18-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"Paroisse Sainte-Th\u00e9r\u00e8se\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-17T14:34:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.saintetheresechalons.com\\\/index.php\\\/jeunes-7-18-ans\\\/\",\"url\":\"https:\\\/\\\/www.saintetheresechalons.com\\\/index.php\\\/jeunes-7-18-ans\\\/\",\"name\":\"Jeunes (7 - 18 ans) - Paroisse Sainte-Th\u00e9r\u00e8se\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.saintetheresechalons.com\\\/#website\"},\"datePublished\":\"2024-09-26T08:52:48+00:00\",\"dateModified\":\"2026-01-17T14:34:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.saintetheresechalons.com\\\/index.php\\\/jeunes-7-18-ans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.saintetheresechalons.com\\\/index.php\\\/jeunes-7-18-ans\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.saintetheresechalons.com\\\/index.php\\\/jeunes-7-18-ans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.saintetheresechalons.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jeunes (7 &#8211; 18 ans)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.saintetheresechalons.com\\\/#website\",\"url\":\"https:\\\/\\\/www.saintetheresechalons.com\\\/\",\"name\":\"Paroisse Sainte-Th\u00e9r\u00e8se\",\"description\":\"Eglise catholique \u00e0 Ch\u00e2lons-En-Champagne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.saintetheresechalons.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jeunes (7 - 18 ans) - Paroisse Sainte-Th\u00e9r\u00e8se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.saintetheresechalons.com\/index.php\/jeunes-7-18-ans\/","og_locale":"fr_FR","og_type":"article","og_title":"Jeunes (7 - 18 ans) - Paroisse Sainte-Th\u00e9r\u00e8se","og_description":"Il est possible de pr\u00e9parer le bapt\u00eame \u00e0 tout \u00e2ge Trois groupes existent sur le doyenn\u00e9, un pour les primaires, un pour les coll\u00e9giens et un pour les lyc\u00e9ens. Pour ... [Read more...]","og_url":"https:\/\/www.saintetheresechalons.com\/index.php\/jeunes-7-18-ans\/","og_site_name":"Paroisse Sainte-Th\u00e9r\u00e8se","article_modified_time":"2026-01-17T14:34:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.saintetheresechalons.com\/index.php\/jeunes-7-18-ans\/","url":"https:\/\/www.saintetheresechalons.com\/index.php\/jeunes-7-18-ans\/","name":"Jeunes (7 - 18 ans) - Paroisse Sainte-Th\u00e9r\u00e8se","isPartOf":{"@id":"https:\/\/www.saintetheresechalons.com\/#website"},"datePublished":"2024-09-26T08:52:48+00:00","dateModified":"2026-01-17T14:34:02+00:00","breadcrumb":{"@id":"https:\/\/www.saintetheresechalons.com\/index.php\/jeunes-7-18-ans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.saintetheresechalons.com\/index.php\/jeunes-7-18-ans\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.saintetheresechalons.com\/index.php\/jeunes-7-18-ans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.saintetheresechalons.com\/"},{"@type":"ListItem","position":2,"name":"Jeunes (7 &#8211; 18 ans)"}]},{"@type":"WebSite","@id":"https:\/\/www.saintetheresechalons.com\/#website","url":"https:\/\/www.saintetheresechalons.com\/","name":"Paroisse Sainte-Th\u00e9r\u00e8se","description":"Eglise catholique \u00e0 Ch\u00e2lons-En-Champagne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.saintetheresechalons.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.saintetheresechalons.com\/index.php\/wp-json\/wp\/v2\/pages\/949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saintetheresechalons.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.saintetheresechalons.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.saintetheresechalons.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saintetheresechalons.com\/index.php\/wp-json\/wp\/v2\/comments?post=949"}],"version-history":[{"count":2,"href":"https:\/\/www.saintetheresechalons.com\/index.php\/wp-json\/wp\/v2\/pages\/949\/revisions"}],"predecessor-version":[{"id":1248,"href":"https:\/\/www.saintetheresechalons.com\/index.php\/wp-json\/wp\/v2\/pages\/949\/revisions\/1248"}],"wp:attachment":[{"href":"https:\/\/www.saintetheresechalons.com\/index.php\/wp-json\/wp\/v2\/media?parent=949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}